{"id":11081,"date":"2024-09-20T19:33:09","date_gmt":"2024-09-20T17:33:09","guid":{"rendered":"https:\/\/fleurdesfleurs.nl\/product\/giraffe-little-dreamer-baby-elephant-naturel-gold\/"},"modified":"2025-07-30T11:02:06","modified_gmt":"2025-07-30T09:02:06","slug":"giraffe-little-dreamer-baby-elephant-naturel-gold","status":"publish","type":"product","link":"https:\/\/fleurdesfleurs.nl\/en\/product\/giraffe-little-dreamer-baby-elephant-naturel-gold\/","title":{"rendered":"Giraffe, Little dreamer  baby elephant naturel gold"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":11032,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[163],"product_tag":[],"class_list":["post-11081","product","type-product","status-publish","has-post-thumbnail","product_cat-wallpapers-en","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giraffe, Little dreamer baby elephant naturel gold - Fleurdesfleurs.nl<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fleurdesfleurs.nl\/en\/product\/giraffe-little-dreamer-baby-elephant-naturel-gold\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giraffe, Little dreamer baby elephant naturel gold - Fleurdesfleurs.nl\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fleurdesfleurs.nl\/en\/product\/giraffe-little-dreamer-baby-elephant-naturel-gold\/\" \/>\n<meta property=\"og:site_name\" content=\"Fleurdesfleurs.nl\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-30T09:02:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fleurdesfleurs.nl\/wp-content\/uploads\/2024\/09\/1.-giraffe-dreamer-elephant-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2308\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fleurdesfleurs.nl\\\/en\\\/product\\\/giraffe-little-dreamer-baby-elephant-naturel-gold\\\/\",\"url\":\"https:\\\/\\\/fleurdesfleurs.nl\\\/en\\\/product\\\/giraffe-little-dreamer-baby-elephant-naturel-gold\\\/\",\"name\":\"Giraffe, Little dreamer baby elephant naturel gold - Fleurdesfleurs.nl\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fleurdesfleurs.nl\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fleurdesfleurs.nl\\\/en\\\/product\\\/giraffe-little-dreamer-baby-elephant-naturel-gold\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fleurdesfleurs.nl\\\/en\\\/product\\\/giraffe-little-dreamer-baby-elephant-naturel-gold\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fleurdesfleurs.nl\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/1.-giraffe-dreamer-elephant-scaled.jpg\",\"datePublished\":\"2024-09-20T17:33:09+00:00\",\"dateModified\":\"2025-07-30T09:02:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fleurdesfleurs.nl\\\/en\\\/product\\\/giraffe-little-dreamer-baby-elephant-naturel-gold\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fleurdesfleurs.nl\\\/en\\\/product\\\/giraffe-little-dreamer-baby-elephant-naturel-gold\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fleurdesfleurs.nl\\\/en\\\/product\\\/giraffe-little-dreamer-baby-elephant-naturel-gold\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fleurdesfleurs.nl\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/1.-giraffe-dreamer-elephant-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/fleurdesfleurs.nl\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/1.-giraffe-dreamer-elephant-scaled.jpg\",\"width\":2560,\"height\":2308},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fleurdesfleurs.nl\\\/en\\\/product\\\/giraffe-little-dreamer-baby-elephant-naturel-gold\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/fleurdesfleurs.nl\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giraffe, Little dreamer baby elephant naturel gold\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fleurdesfleurs.nl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/fleurdesfleurs.nl\\\/en\\\/\",\"name\":\"Fleurdesfleurs.nl\",\"description\":\"Interior Design\",\"publisher\":{\"@id\":\"https:\\\/\\\/fleurdesfleurs.nl\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fleurdesfleurs.nl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fleurdesfleurs.nl\\\/en\\\/#organization\",\"name\":\"Fleurdesfleurs.nl\",\"url\":\"https:\\\/\\\/fleurdesfleurs.nl\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fleurdesfleurs.nl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fleurdesfleurs.nl\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-Logo-sticker-9.-6-cm-.jpg\",\"contentUrl\":\"https:\\\/\\\/fleurdesfleurs.nl\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-Logo-sticker-9.-6-cm-.jpg\",\"width\":1033,\"height\":594,\"caption\":\"Fleurdesfleurs.nl\"},\"image\":{\"@id\":\"https:\\\/\\\/fleurdesfleurs.nl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giraffe, Little dreamer baby elephant naturel gold - Fleurdesfleurs.nl","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fleurdesfleurs.nl\/en\/product\/giraffe-little-dreamer-baby-elephant-naturel-gold\/","og_locale":"en_US","og_type":"article","og_title":"Giraffe, Little dreamer baby elephant naturel gold - Fleurdesfleurs.nl","og_url":"https:\/\/fleurdesfleurs.nl\/en\/product\/giraffe-little-dreamer-baby-elephant-naturel-gold\/","og_site_name":"Fleurdesfleurs.nl","article_modified_time":"2025-07-30T09:02:06+00:00","og_image":[{"width":2560,"height":2308,"url":"https:\/\/fleurdesfleurs.nl\/wp-content\/uploads\/2024\/09\/1.-giraffe-dreamer-elephant-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fleurdesfleurs.nl\/en\/product\/giraffe-little-dreamer-baby-elephant-naturel-gold\/","url":"https:\/\/fleurdesfleurs.nl\/en\/product\/giraffe-little-dreamer-baby-elephant-naturel-gold\/","name":"Giraffe, Little dreamer baby elephant naturel gold - Fleurdesfleurs.nl","isPartOf":{"@id":"https:\/\/fleurdesfleurs.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fleurdesfleurs.nl\/en\/product\/giraffe-little-dreamer-baby-elephant-naturel-gold\/#primaryimage"},"image":{"@id":"https:\/\/fleurdesfleurs.nl\/en\/product\/giraffe-little-dreamer-baby-elephant-naturel-gold\/#primaryimage"},"thumbnailUrl":"https:\/\/fleurdesfleurs.nl\/wp-content\/uploads\/2024\/09\/1.-giraffe-dreamer-elephant-scaled.jpg","datePublished":"2024-09-20T17:33:09+00:00","dateModified":"2025-07-30T09:02:06+00:00","breadcrumb":{"@id":"https:\/\/fleurdesfleurs.nl\/en\/product\/giraffe-little-dreamer-baby-elephant-naturel-gold\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fleurdesfleurs.nl\/en\/product\/giraffe-little-dreamer-baby-elephant-naturel-gold\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fleurdesfleurs.nl\/en\/product\/giraffe-little-dreamer-baby-elephant-naturel-gold\/#primaryimage","url":"https:\/\/fleurdesfleurs.nl\/wp-content\/uploads\/2024\/09\/1.-giraffe-dreamer-elephant-scaled.jpg","contentUrl":"https:\/\/fleurdesfleurs.nl\/wp-content\/uploads\/2024\/09\/1.-giraffe-dreamer-elephant-scaled.jpg","width":2560,"height":2308},{"@type":"BreadcrumbList","@id":"https:\/\/fleurdesfleurs.nl\/en\/product\/giraffe-little-dreamer-baby-elephant-naturel-gold\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Shop","item":"https:\/\/fleurdesfleurs.nl\/shop\/"},{"@type":"ListItem","position":2,"name":"Giraffe, Little dreamer baby elephant naturel gold"}]},{"@type":"WebSite","@id":"https:\/\/fleurdesfleurs.nl\/en\/#website","url":"https:\/\/fleurdesfleurs.nl\/en\/","name":"Fleurdesfleurs.nl","description":"Interior Design","publisher":{"@id":"https:\/\/fleurdesfleurs.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fleurdesfleurs.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fleurdesfleurs.nl\/en\/#organization","name":"Fleurdesfleurs.nl","url":"https:\/\/fleurdesfleurs.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fleurdesfleurs.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/fleurdesfleurs.nl\/wp-content\/uploads\/2023\/07\/cropped-Logo-sticker-9.-6-cm-.jpg","contentUrl":"https:\/\/fleurdesfleurs.nl\/wp-content\/uploads\/2023\/07\/cropped-Logo-sticker-9.-6-cm-.jpg","width":1033,"height":594,"caption":"Fleurdesfleurs.nl"},"image":{"@id":"https:\/\/fleurdesfleurs.nl\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/fleurdesfleurs.nl\/en\/wp-json\/wp\/v2\/product\/11081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fleurdesfleurs.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fleurdesfleurs.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/fleurdesfleurs.nl\/en\/wp-json\/wp\/v2\/comments?post=11081"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fleurdesfleurs.nl\/en\/wp-json\/wp\/v2\/media\/11032"}],"wp:attachment":[{"href":"https:\/\/fleurdesfleurs.nl\/en\/wp-json\/wp\/v2\/media?parent=11081"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/fleurdesfleurs.nl\/en\/wp-json\/wp\/v2\/product_brand?post=11081"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fleurdesfleurs.nl\/en\/wp-json\/wp\/v2\/product_cat?post=11081"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fleurdesfleurs.nl\/en\/wp-json\/wp\/v2\/product_tag?post=11081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}